{"id":78,"count":1,"description":"","link":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/","name":"Champagne","slug":"champagne-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Champagne archivos - Temps Barcelona<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Champagne archivos - Temps Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Temps Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/\",\"url\":\"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/\",\"name\":\"Champagne archivos - Temps Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.tempsbarcelona.com\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tempsbarcelona.com\/fr\/temps-barcelona\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Champagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tempsbarcelona.com\/fr\/#website\",\"url\":\"https:\/\/www.tempsbarcelona.com\/fr\/\",\"name\":\"Temps Barcelona\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tempsbarcelona.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Champagne archivos - Temps Barcelona","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Champagne archivos - Temps Barcelona","og_url":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/","og_site_name":"Temps Barcelona","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/","url":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/","name":"Champagne archivos - Temps Barcelona","isPartOf":{"@id":"https:\/\/www.tempsbarcelona.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tempsbarcelona.com\/fr\/champagne-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tempsbarcelona.com\/fr\/temps-barcelona\/"},{"@type":"ListItem","position":2,"name":"Champagne"}]},{"@type":"WebSite","@id":"https:\/\/www.tempsbarcelona.com\/fr\/#website","url":"https:\/\/www.tempsbarcelona.com\/fr\/","name":"Temps Barcelona","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tempsbarcelona.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tempsbarcelona.com\/fr\/wp-json\/wp\/v2\/categories\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tempsbarcelona.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.tempsbarcelona.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.tempsbarcelona.com\/fr\/wp-json\/wp\/v2\/posts?categories=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}